{"id":4067,"date":"2019-08-09T12:27:05","date_gmt":"2019-08-09T10:27:05","guid":{"rendered":"https:\/\/nodusbarbera.cat\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\/"},"modified":"2020-02-18T16:16:57","modified_gmt":"2020-02-18T14:16:57","slug":"dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento","status":"publish","type":"post","link":"https:\/\/nodusbarbera.cat\/es\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\/","title":{"rendered":"Dos empresas de Barber\u00e0 del Vall\u00e8s participan en el programa ACELERA EL CRECIMIENTO"},"content":{"rendered":"<p>Las empresas <a href=\"http:\/\/www.hidrochlor.com\" target=\"_blank\" rel=\"noopener noreferrer\">HIDROCHLOR<\/a> y <a href=\"https:\/\/flojim.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">FLOJIM<\/a>, de Barber\u00e0 del Vall\u00e8s, han sido seleccionadas para participar en el programa <a href=\"http:\/\/www.acceleraelcreixement.com\/es\/\" target=\"_blank\" rel=\"noopener noreferrer\">ACELERA EL CRECIMIENTO<\/a>, donde s\u00f3lo 50 empresas de la provincia pueden formar parte.<!--more-->ACELERA EL CRECIMIENTO es un programa de alto rendimiento para el acompa\u00f1amiento a pymes durante 9 meses, de la mano de expertos en \u00e1reas de gesti\u00f3n empresarial, donde se elabora un plan de crecimiento y se crea un plan para su ejecuci\u00f3n.<\/p>\n<p>Desde el 2012, <a href=\"https:\/\/www.pimec.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">PIMEC <\/a>y la <a href=\"https:\/\/www.diba.cat\/\" target=\"_blank\" rel=\"noopener noreferrer\">Diputaci\u00f3 de Barcelona<\/a> organizan e impulsan cada a\u00f1o el programa, en el que empresario y trabajadores unen esfuerzos para colaborar con expertos en crecimiento empresarial que les ofrecen apoyo durante los 9 meses.<\/p>\n<p>La sesi\u00f3n inaugural y de presentaci\u00f3n se prev\u00e9 para el 26 de septiembre de este a\u00f1o. Ten\u00e9is m\u00e1s informaci\u00f3n en el <a href=\"http:\/\/www.acceleraelcreixement.com\/es\/\" target=\"_blank\" rel=\"noopener noreferrer\">sitio web de ACELERA EL CRECIMIENTO.<span style=\"color: #333333;\"><\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las empresas HIDROCHLOR y FLOJIM, de Barber\u00e0 del Vall\u00e8s, han sido seleccionadas para participar en el programa ACELERA EL CRECIMIENTO, donde s\u00f3lo 50 empresas de la provincia pueden formar parte.<\/p>\n","protected":false},"author":2,"featured_media":3312,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-4067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dos empresas de Barber\u00e0 del Vall\u00e8s participan en el programa ACELERA EL CRECIMIENTO - Nodus Barber\u00e0<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nodusbarbera.cat\/es\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dos empresas de Barber\u00e0 del Vall\u00e8s participan en el programa ACELERA EL CRECIMIENTO - Nodus Barber\u00e0\" \/>\n<meta property=\"og:description\" content=\"Las empresas HIDROCHLOR y FLOJIM, de Barber\u00e0 del Vall\u00e8s, han sido seleccionadas para participar en el programa ACELERA EL CRECIMIENTO, donde s\u00f3lo 50 empresas de la provincia pueden formar parte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nodusbarbera.cat\/es\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Nodus Barber\u00e0\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nodusbarbera\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-09T10:27:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-18T14:16:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/nodusbarbera.cat\/wp-content\/uploads\/accelera-creixement-nodus2.jpg?fit=915%2C602&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"915\" \/>\n\t<meta property=\"og:image:height\" content=\"602\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webmaster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nodusbarbera\" \/>\n<meta name=\"twitter:site\" content=\"@nodusbarbera\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmaster\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nodusbarbera.cat\\\/es\\\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nodusbarbera.cat\\\/es\\\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\\\/\"},\"author\":{\"name\":\"webmaster\",\"@id\":\"https:\\\/\\\/nodusbarbera.cat\\\/#\\\/schema\\\/person\\\/f3356bf21f659e7e41d958bbb784cfe4\"},\"headline\":\"Dos empresas de Barber\u00e0 del Vall\u00e8s participan en el programa ACELERA EL CRECIMIENTO\",\"datePublished\":\"2019-08-09T10:27:05+00:00\",\"dateModified\":\"2020-02-18T14:16:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nodusbarbera.cat\\\/es\\\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\\\/\"},\"wordCount\":159,\"publisher\":{\"@id\":\"https:\\\/\\\/nodusbarbera.cat\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nodusbarbera.cat\\\/es\\\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nodusbarbera.cat\\\/wp-content\\\/uploads\\\/accelera-creixement-nodus2.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nodusbarbera.cat\\\/es\\\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\\\/\",\"url\":\"https:\\\/\\\/nodusbarbera.cat\\\/es\\\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\\\/\",\"name\":\"Dos empresas de Barber\u00e0 del Vall\u00e8s participan en el programa ACELERA EL CRECIMIENTO - Nodus Barber\u00e0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nodusbarbera.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nodusbarbera.cat\\\/es\\\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nodusbarbera.cat\\\/es\\\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nodusbarbera.cat\\\/wp-content\\\/uploads\\\/accelera-creixement-nodus2.jpg\",\"datePublished\":\"2019-08-09T10:27:05+00:00\",\"dateModified\":\"2020-02-18T14:16:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nodusbarbera.cat\\\/es\\\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nodusbarbera.cat\\\/es\\\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nodusbarbera.cat\\\/es\\\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nodusbarbera.cat\\\/wp-content\\\/uploads\\\/accelera-creixement-nodus2.jpg\",\"contentUrl\":\"https:\\\/\\\/nodusbarbera.cat\\\/wp-content\\\/uploads\\\/accelera-creixement-nodus2.jpg\",\"width\":915,\"height\":602},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nodusbarbera.cat\\\/es\\\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/nodusbarbera.cat\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dos empresas de Barber\u00e0 del Vall\u00e8s participan en el programa ACELERA EL CRECIMIENTO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nodusbarbera.cat\\\/#website\",\"url\":\"https:\\\/\\\/nodusbarbera.cat\\\/\",\"name\":\"Nodus Barber\u00e0\",\"description\":\"Lloguer d&#039;oficines i despatxos a Barber\u00e0 del Vall\u00e8s, Barcelona.\",\"publisher\":{\"@id\":\"https:\\\/\\\/nodusbarbera.cat\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nodusbarbera.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nodusbarbera.cat\\\/#organization\",\"name\":\"Nodus Barber\u00e0\",\"url\":\"https:\\\/\\\/nodusbarbera.cat\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nodusbarbera.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/nodusbarbera.cat\\\/wp-content\\\/uploads\\\/logo-footer-250.png?fit=250%2C231&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/nodusbarbera.cat\\\/wp-content\\\/uploads\\\/logo-footer-250.png?fit=250%2C231&ssl=1\",\"width\":250,\"height\":231,\"caption\":\"Nodus Barber\u00e0\"},\"image\":{\"@id\":\"https:\\\/\\\/nodusbarbera.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nodusbarbera\",\"https:\\\/\\\/x.com\\\/nodusbarbera\",\"https:\\\/\\\/www.instagram.com\\\/nodusbarbera\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/nodus-barbera\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCLJYdjFDfFQP1aGYuzUFd6A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nodusbarbera.cat\\\/#\\\/schema\\\/person\\\/f3356bf21f659e7e41d958bbb784cfe4\",\"name\":\"webmaster\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73641b46ed44db8f663f428fc279f909e9f48696e06a190b1e330f4634071610?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73641b46ed44db8f663f428fc279f909e9f48696e06a190b1e330f4634071610?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73641b46ed44db8f663f428fc279f909e9f48696e06a190b1e330f4634071610?s=96&d=mm&r=g\",\"caption\":\"webmaster\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dos empresas de Barber\u00e0 del Vall\u00e8s participan en el programa ACELERA EL CRECIMIENTO - Nodus Barber\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nodusbarbera.cat\/es\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\/","og_locale":"es_ES","og_type":"article","og_title":"Dos empresas de Barber\u00e0 del Vall\u00e8s participan en el programa ACELERA EL CRECIMIENTO - Nodus Barber\u00e0","og_description":"Las empresas HIDROCHLOR y FLOJIM, de Barber\u00e0 del Vall\u00e8s, han sido seleccionadas para participar en el programa ACELERA EL CRECIMIENTO, donde s\u00f3lo 50 empresas de la provincia pueden formar parte.","og_url":"https:\/\/nodusbarbera.cat\/es\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\/","og_site_name":"Nodus Barber\u00e0","article_publisher":"https:\/\/www.facebook.com\/nodusbarbera","article_published_time":"2019-08-09T10:27:05+00:00","article_modified_time":"2020-02-18T14:16:57+00:00","og_image":[{"width":915,"height":602,"url":"https:\/\/i1.wp.com\/nodusbarbera.cat\/wp-content\/uploads\/accelera-creixement-nodus2.jpg?fit=915%2C602&ssl=1","type":"image\/jpeg"}],"author":"webmaster","twitter_card":"summary_large_image","twitter_creator":"@nodusbarbera","twitter_site":"@nodusbarbera","twitter_misc":{"Escrito por":"webmaster","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nodusbarbera.cat\/es\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\/#article","isPartOf":{"@id":"https:\/\/nodusbarbera.cat\/es\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\/"},"author":{"name":"webmaster","@id":"https:\/\/nodusbarbera.cat\/#\/schema\/person\/f3356bf21f659e7e41d958bbb784cfe4"},"headline":"Dos empresas de Barber\u00e0 del Vall\u00e8s participan en el programa ACELERA EL CRECIMIENTO","datePublished":"2019-08-09T10:27:05+00:00","dateModified":"2020-02-18T14:16:57+00:00","mainEntityOfPage":{"@id":"https:\/\/nodusbarbera.cat\/es\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\/"},"wordCount":159,"publisher":{"@id":"https:\/\/nodusbarbera.cat\/#organization"},"image":{"@id":"https:\/\/nodusbarbera.cat\/es\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/nodusbarbera.cat\/wp-content\/uploads\/accelera-creixement-nodus2.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/nodusbarbera.cat\/es\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\/","url":"https:\/\/nodusbarbera.cat\/es\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\/","name":"Dos empresas de Barber\u00e0 del Vall\u00e8s participan en el programa ACELERA EL CRECIMIENTO - Nodus Barber\u00e0","isPartOf":{"@id":"https:\/\/nodusbarbera.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nodusbarbera.cat\/es\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\/#primaryimage"},"image":{"@id":"https:\/\/nodusbarbera.cat\/es\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/nodusbarbera.cat\/wp-content\/uploads\/accelera-creixement-nodus2.jpg","datePublished":"2019-08-09T10:27:05+00:00","dateModified":"2020-02-18T14:16:57+00:00","breadcrumb":{"@id":"https:\/\/nodusbarbera.cat\/es\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nodusbarbera.cat\/es\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nodusbarbera.cat\/es\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\/#primaryimage","url":"https:\/\/nodusbarbera.cat\/wp-content\/uploads\/accelera-creixement-nodus2.jpg","contentUrl":"https:\/\/nodusbarbera.cat\/wp-content\/uploads\/accelera-creixement-nodus2.jpg","width":915,"height":602},{"@type":"BreadcrumbList","@id":"https:\/\/nodusbarbera.cat\/es\/dos-empresas-de-barbera-del-valles-participan-en-el-programa-acelera-el-crecimiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/nodusbarbera.cat\/"},{"@type":"ListItem","position":2,"name":"Dos empresas de Barber\u00e0 del Vall\u00e8s participan en el programa ACELERA EL CRECIMIENTO"}]},{"@type":"WebSite","@id":"https:\/\/nodusbarbera.cat\/#website","url":"https:\/\/nodusbarbera.cat\/","name":"Nodus Barber\u00e0","description":"Lloguer d&#039;oficines i despatxos a Barber\u00e0 del Vall\u00e8s, Barcelona.","publisher":{"@id":"https:\/\/nodusbarbera.cat\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nodusbarbera.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nodusbarbera.cat\/#organization","name":"Nodus Barber\u00e0","url":"https:\/\/nodusbarbera.cat\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nodusbarbera.cat\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/nodusbarbera.cat\/wp-content\/uploads\/logo-footer-250.png?fit=250%2C231&ssl=1","contentUrl":"https:\/\/i0.wp.com\/nodusbarbera.cat\/wp-content\/uploads\/logo-footer-250.png?fit=250%2C231&ssl=1","width":250,"height":231,"caption":"Nodus Barber\u00e0"},"image":{"@id":"https:\/\/nodusbarbera.cat\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nodusbarbera","https:\/\/x.com\/nodusbarbera","https:\/\/www.instagram.com\/nodusbarbera\/","https:\/\/www.linkedin.com\/company\/nodus-barbera\/","https:\/\/www.youtube.com\/channel\/UCLJYdjFDfFQP1aGYuzUFd6A"]},{"@type":"Person","@id":"https:\/\/nodusbarbera.cat\/#\/schema\/person\/f3356bf21f659e7e41d958bbb784cfe4","name":"webmaster","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/73641b46ed44db8f663f428fc279f909e9f48696e06a190b1e330f4634071610?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/73641b46ed44db8f663f428fc279f909e9f48696e06a190b1e330f4634071610?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/73641b46ed44db8f663f428fc279f909e9f48696e06a190b1e330f4634071610?s=96&d=mm&r=g","caption":"webmaster"}}]}},"_links":{"self":[{"href":"https:\/\/nodusbarbera.cat\/es\/wp-json\/wp\/v2\/posts\/4067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nodusbarbera.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nodusbarbera.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nodusbarbera.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nodusbarbera.cat\/es\/wp-json\/wp\/v2\/comments?post=4067"}],"version-history":[{"count":1,"href":"https:\/\/nodusbarbera.cat\/es\/wp-json\/wp\/v2\/posts\/4067\/revisions"}],"predecessor-version":[{"id":4284,"href":"https:\/\/nodusbarbera.cat\/es\/wp-json\/wp\/v2\/posts\/4067\/revisions\/4284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nodusbarbera.cat\/es\/wp-json\/wp\/v2\/media\/3312"}],"wp:attachment":[{"href":"https:\/\/nodusbarbera.cat\/es\/wp-json\/wp\/v2\/media?parent=4067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nodusbarbera.cat\/es\/wp-json\/wp\/v2\/categories?post=4067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nodusbarbera.cat\/es\/wp-json\/wp\/v2\/tags?post=4067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}